{"id":6241,"date":"2022-10-20T09:43:30","date_gmt":"2022-10-20T00:43:30","guid":{"rendered":"http:\/\/www.sasebo-shakyo.or.jp\/news\/?p=6241"},"modified":"2022-10-27T09:28:51","modified_gmt":"2022-10-27T00:28:51","slug":"%e4%bb%a4%e5%92%8c4%e5%b9%b4%e5%ba%a6%e7%ac%ac%ef%bc%92%e5%9b%9e%e3%81%8a%e3%82%82%e3%82%84%e3%81%84%e3%83%8d%e3%83%83%e3%83%88%e3%82%88%e3%81%97%e3%81%84%e3%82%b5%e3%83%9d%e3%83%bc%e3%82%bf%e3%83%bc","status":"publish","type":"post","link":"http:\/\/www.sasebo-shakyo.or.jp\/news\/2022\/10\/20\/%e4%bb%a4%e5%92%8c4%e5%b9%b4%e5%ba%a6%e7%ac%ac%ef%bc%92%e5%9b%9e%e3%81%8a%e3%82%82%e3%82%84%e3%81%84%e3%83%8d%e3%83%83%e3%83%88%e3%82%88%e3%81%97%e3%81%84%e3%82%b5%e3%83%9d%e3%83%bc%e3%82%bf%e3%83%bc\/","title":{"rendered":"\u4ee4\u548c4\u5e74\u5ea6\u7b2c\uff12\u56de\u304a\u3082\u3084\u3044\u30cd\u30c3\u30c8\u3088\u3057\u3044\u30b5\u30dd\u30fc\u30bf\u30fc\u4f1a\u958b\u50ac\u81ea\u52d5\u4e0b\u66f8\u304d"},"content":{"rendered":"<p style=\"text-align: center\"><span style=\"font-size: 24pt\">\u4ee4\u548c4\u5e74\u5ea6<\/span><span style=\"font-size: 24pt\">\u7b2c\uff12\u56de<\/span><\/p>\r\n<p style=\"text-align: center\"><span style=\"font-size: 24pt\">\u304a\u3082\u3084\u3044\u30cd\u30c3\u30c8\u3088\u3057\u3044\u30b5\u30dd\u30fc\u30bf\u30fc\u4f1a\u958b\u50ac<\/span><\/p>\r\n<p>&nbsp;<\/p>\r\n<p>\u4ee4\u548c\uff14\u5e748\u670827\u65e5\uff08\u571f\uff09\u3001\u4ee4\u548c4\u5e74\u5ea6\u7b2c2\u56de\u304a\u3082\u3084\u3044\u30cd\u30c3\u30c8\u3088\u3057\u3044\u30b5\u30dd\u30fc\u30bf\u30fc\u4f1a\u306e\u652f\u63f4\u3068\u3057\u3066\u53c2\u52a0\u3057\u307e\u3057\u305f\u3002\u30b3\u30ed\u30ca\u306e\u611f\u67d3\u4e88\u9632\u5bfe\u7b56\u306e\u305f\u3081\u6642\u9593\u3092\u77ed\u7e2e\u3057\u3066\u884c\u308f\u308c\u307e\u3057\u305f\u3002\u4eca\u56de\u306f\u3001\u4ecb\u8b77\u4e88\u9632\u4f53\u64cd\u3084\u30b5\u30ed\u30f3\u3067\u6d3b\u8e8d\u3057\u3066\u3044\u308b\u30b5\u30dd\u30fc\u30bf\u30fc\u3055\u3093\u306e\u7d39\u4ecb\u3084\u6700\u8fd1\u306e\u751f\u6d3b\u652f\u63f4\u306e\u69d8\u5b50\u304c\u7d39\u4ecb\u3055\u308c\u307e\u3057\u305f\u3002\u5f8c\u534a\u306f\u3001\u65b0\u305f\u306b\u767a\u8db3\u3059\u308b\u3001\u5916\u51fa\u652f\u63f4\u3082\u884c\u3046\u30dc\u30e9\u30f3\u30c6\u30a3\u30a2\u56e3\u4f53\u300c\u3088\u3057\u3044\u3053\u4f1a\u300d\u306e\u7d39\u4ecb\u304c\u3042\u308a\u3001\u8cdb\u540c\u8005\u3057\u3066\u4f1a\u54e1\u306b\u306a\u308b\u7686\u3055\u3093\u306e\u767b\u9332\u304c\u884c\u308f\u308c\u307e\u3057\u305f\u3002<\/p>\r\n<p>&nbsp;<\/p>\r\n<p style=\"text-align: center\"><span style=\"font-size: 18pt\">\u3010\u4ecb\u8b77\u4e88\u9632\u4f53\u64cd\u306e\u6307\u5c0e\u3084\u4e16\u8a71\u3092\u3057\u3066\u3044\u308b\u30b5\u30dd\u30fc\u30bf\u30fc\u306e\u7686\u3055\u3093\u3011<\/span><\/p>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6243 aligncenter\" src=\"\/cms\/contents\/sites\/2\/2022\/09\/20220824_104955.jpg\" alt=\"\" width=\"665\" height=\"499\" srcset=\"\/cms\/contents\/sites\/2\/2022\/09\/20220824_104955.jpg 800w, \/cms\/contents\/sites\/2\/2022\/09\/20220824_104955-300x225.jpg 300w, \/cms\/contents\/sites\/2\/2022\/09\/20220824_104955-768x576.jpg 768w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/p>\r\n<p>\u4e0a\u306e\u5199\u771f\u306f\u30b7\u30cb\u30a2\u5143\u6c17\u30af\u30e9\u30d6\u306e\u6d3b\u52d5\u306e\u69d8\u5b50\u3067\u3059\u3002\u5168\u8eab\u306e\u30b9\u30c8\u30ec\u30c3\u30c1\u304b\u3089\u3001\u30ea\u30ba\u30e0\u30c0\u30f3\u30b9\u307e\u3067\u3001\uff18\uff10\u6b73\u4ee3\u306e\u30b5\u30dd\u30fc\u30bf\u30fc\u3055\u3093\u304c\u3001\u6307\u5c0e\u8005\u3068\u3057\u3066\u73fe\u5f79\u3067\u6d3b\u8e8d\u3055\u308c\u3066\u3044\u308b\u3068\u3053\u308d\u3067\u3059\u3002<\/p>\r\n<p>&nbsp;<\/p>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6244 aligncenter\" src=\"\/cms\/contents\/sites\/2\/2022\/09\/20220516_103655.jpg\" alt=\"\" width=\"667\" height=\"500\" srcset=\"\/cms\/contents\/sites\/2\/2022\/09\/20220516_103655.jpg 800w, \/cms\/contents\/sites\/2\/2022\/09\/20220516_103655-300x225.jpg 300w, \/cms\/contents\/sites\/2\/2022\/09\/20220516_103655-768x576.jpg 768w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/p>\r\n<p>\u4e0a\u306e\u5199\u771f\u306f\u3001\u30b5\u30ed\u30f3\u6d3b\u52d5\u306e\u69d8\u5b50\u3067\u3059\u3002\u3054\u304d\u3076\u308a\u3060\u3093\u3054\u3065\u304f\u308a\u3092\u30b5\u30dd\u30fc\u30bf\u30fc\u3055\u3093\u3068\u9ad8\u9f62\u8005\u306e\u65b9\u304c\u4e00\u7dd2\u306b\u3055\u308c\u3066\u3044\u308b\u3068\u3053\u308d\u3067\u3059\u3002<\/p>\r\n<p>&nbsp;<\/p>\r\n<p style=\"text-align: center\"><span style=\"font-size: 18pt\">\u3010\u5916\u51fa\u652f\u63f4\u3082\u884c\u3046\u65b0\u305f\u306a\u56e3\u4f53\u300c\u3088\u3057\u3044\u3053\u4f1a\u300d\u306e\u7d39\u4ecb\u3068\u767b\u9332\u3011<\/span><\/p>\r\n<p>\u3000\u307e\u305a\u3001\u6d3b\u52d5\u306b\u3042\u305f\u3063\u3066\u306e\u5229\u7528\u6599\u3068\u8b1d\u793c\u91d1\u3001\u5951\u7d04\u66f8\u3001\u898f\u7d04\u7b49\u306b\u3064\u3044\u3066\u8cc7\u6599\u3067\u306e\u8aac\u660e\u304c\u3042\u308a\u307e\u3057\u305f\u3002\u305d\u306e\u5f8c\u3001\u300c\u3088\u3057\u3044\u3053\u4f1a\u300d\u306e\u4f1a\u9577\u304b\u3089\u4f1a\u3078\u306e\u304a\u8a98\u3044\u304c\u3042\u308a\u3001\u8cdb\u540c\u3059\u308b\u7686\u3055\u3093\u304c\u767b\u9332\u3092\u3055\u308c\u307e\u3057\u305f\u3002<\/p>\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6242 aligncenter\" src=\"\/cms\/contents\/sites\/2\/2022\/09\/1661842237719.jpg\" alt=\"\" width=\"675\" height=\"506\" srcset=\"\/cms\/contents\/sites\/2\/2022\/09\/1661842237719.jpg 800w, \/cms\/contents\/sites\/2\/2022\/09\/1661842237719-300x225.jpg 300w, \/cms\/contents\/sites\/2\/2022\/09\/1661842237719-768x576.jpg 768w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/><\/p>\r\n<p>&nbsp;<\/p>\r\n<p>\u3000\u300c\u3088\u3057\u3044\u3053\u4f1a\u300d\u306f\u3001\u3053\u306e\u65e5\u3092\u3082\u3063\u3066\u767a\u8db3\u3057\u3001\u300c\u304a\u3082\u3084\u3044\u30cd\u30c3\u30c8\u3088\u3057\u3044\u300d\u3068\u9023\u643a\u3057\u306a\u304c\u3089\u6d3b\u52d5\u3092\u30b9\u30bf\u30fc\u30c8\u3055\u305b\u308b\u3053\u3068\u306b\u306a\u308a\u307e\u3057\u305f\u3002\u6700\u521d\u306f\u3001\u5409\u4e95\u5730\u57df\u5305\u62ec\u652f\u63f4\u30bb\u30f3\u30bf\u30fc\u3084\u5409\u4e95\u4ecb\u8b77\u4e8b\u696d\u6240\u3001\u4e16\u77e5\u539f\u4ecb\u8b77\u4e8b\u696d\u6240\u306e\u30cb\u30fc\u30ba\u306b\u5fdc\u3048\u308b\u5f62\u3067\u3001\u7121\u7406\u306a\u304f\u6d3b\u52d5\u3059\u308b\u3068\u3044\u3046\u3053\u3068\u3067\u3059\u3002<\/p>","protected":false},"excerpt":{"rendered":"\u4ee4\u548c4\u5e74\u5ea6\u7b2c\uff12\u56de \u304a\u3082\u3084\u3044\u30cd\u30c3\u30c8\u3088\u3057\u3044\u30b5\u30dd\u30fc\u30bf\u30fc\u4f1a\u958b\u50ac &nbsp; \u4ee4\u548c\uff14\u5e748\u670827\u65e5\uff08\u571f\uff09\u3001\u4ee4\u548c4\u5e74\u5ea6\u7b2c2\u56de\u304a\u3082\u3084\u3044\u30cd\u30c3\u30c8\u3088\u3057\u3044\u30b5\u30dd\u30fc\u30bf\u30fc\u4f1a\u306e\u652f\u63f4\u3068\u3057\u3066\u53c2\u52a0\u3057\u307e\u3057\u305f\u3002\u30b3\u30ed\u30ca\u306e\u611f\u67d3\u4e88\u9632\u5bfe\u7b56\u306e\u305f\u3081\u6642\u9593\u3092\u77ed\u7e2e\u3057\u3066\u884c\u308f\u308c\u307e\u3057 [&hellip;]","protected":false},"author":19,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6241","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 15:43:18","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"http:\/\/www.sasebo-shakyo.or.jp\/news\/wp-json\/wp\/v2\/posts\/6241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.sasebo-shakyo.or.jp\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.sasebo-shakyo.or.jp\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.sasebo-shakyo.or.jp\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"http:\/\/www.sasebo-shakyo.or.jp\/news\/wp-json\/wp\/v2\/comments?post=6241"}],"version-history":[{"count":5,"href":"http:\/\/www.sasebo-shakyo.or.jp\/news\/wp-json\/wp\/v2\/posts\/6241\/revisions"}],"predecessor-version":[{"id":6253,"href":"http:\/\/www.sasebo-shakyo.or.jp\/news\/wp-json\/wp\/v2\/posts\/6241\/revisions\/6253"}],"wp:attachment":[{"href":"http:\/\/www.sasebo-shakyo.or.jp\/news\/wp-json\/wp\/v2\/media?parent=6241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.sasebo-shakyo.or.jp\/news\/wp-json\/wp\/v2\/categories?post=6241"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.sasebo-shakyo.or.jp\/news\/wp-json\/wp\/v2\/tags?post=6241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}